{"id":1886,"date":"2017-12-17T16:02:41","date_gmt":"2017-12-17T15:02:41","guid":{"rendered":"http:\/\/meta-m.org\/?p=1886"},"modified":"2017-12-22T17:45:53","modified_gmt":"2017-12-22T16:45:53","slug":"malte-une-ile-gangrenee-par-la-corruption","status":"publish","type":"post","link":"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/","title":{"rendered":"<strong>Malte, une \u00eele gangr\u00e9n\u00e9e par la corruption ?<\/strong>"},"content":{"rendered":"<p><em>Un reportage ARTE Regards<\/em><br \/>\n<strong>Le plus petit \u00c9tat membre de l\u2019Union europ\u00e9enne attire des millions de touristes, mais Malte fait aussi r\u00e9guli\u00e8rement les gros titres pour des affaires de corruption et de blanchiment d\u2019argent. Le meurtre de la journaliste Daphne Caruana Galizia a provoqu\u00e9 la stupeur en Europe. Pourquoi a-t-elle \u00e9t\u00e9 tu\u00e9e ? Et comment r\u00e9agit l\u2019UE ?<\/strong><br \/>\n<iframe loading=\"lazy\" allowfullscreen=\"true\" style=\"transition-duration:0;transition-property:no;margin:0 auto;position:relative;display:block;background-color:#000000;\" frameborder=\"0\" scrolling=\"no\" width=\"720\" height=\"406\" src=\"https:\/\/www.arte.tv\/player\/v3\/index.php?json_url=https%3A%2F%2Fapi.arte.tv%2Fapi%2Fplayer%2Fv1%2Fconfig%2Ffr%2F072496-007-A%3Fautostart%3D0%26lifeCycle%3D1&amp;lang=fr_FR&amp;embed=1&amp;mute=0\"><\/iframe><\/p>\n<p>Malte : Daphne Caruana Galizia d\u00e9non\u00e7ait la corruption dans un Etat europ\u00e9en peu ordinaire. Plus petit pays de l\u2019Union avec 430 000 habitants, l\u2019\u00eele m\u00e9diterran\u00e9enne est r\u00e9guli\u00e8rement accus\u00e9e de d\u00e9rive mafieuse. Les opposants et les journalistes \u00e9trangers qui enqu\u00eatent sur le syst\u00e8me maltais critiquent l\u2019absence d\u2019ind\u00e9pendance de la police, de la justice, des m\u00e9dias.<br \/>\nDaphne Caruana Galizia, m\u00e8re de trois fils, n\u2019\u00e9tait pas une journaliste ordinaire. Depuis une dizaine d\u2019ann\u00e9es, elle d\u00e9non\u00e7ait sans rel\u00e2che, sur son blog, Running Commentary,  le blanchiment d\u2019argent \u00e0 grande \u00e9chelle et la corruption dans les milieux dirigeants maltais. Elle le faisait \u00e0 sa mani\u00e8re, brutale, cavali\u00e8re, acerbe, franchissant parfois le pas des attaques personnelles contre les politiques.<br \/>\n<a href=\"http:\/\/www.lemonde.fr\/idees\/article\/2017\/10\/20\/malte-un-etat-europeen-peu-ordinaire_5203726_3232.html\">Article du journal Le Monde<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un reportage ARTE Regards Le plus petit \u00c9tat membre de l\u2019Union europ\u00e9enne attire des millions de touristes, mais Malte fait aussi r\u00e9guli\u00e8rement les gros titres pour des affaires de corruption et de blanchiment d\u2019argent. Le&hellip; <a href=\"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/\">Plus<\/a><\/p>\n","protected":false},"author":2,"featured_media":1894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[112,47,111,110],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Malte, une \u00eele gangr\u00e9n\u00e9e par la corruption ? -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malte, une \u00eele gangr\u00e9n\u00e9e par la corruption ? -\" \/>\n<meta property=\"og:description\" content=\"Un reportage ARTE Regards Le plus petit \u00c9tat membre de l\u2019Union europ\u00e9enne attire des millions de touristes, mais Malte fait aussi r\u00e9guli\u00e8rement les gros titres pour des affaires de corruption et de blanchiment d\u2019argent. Le&hellip; Plus\" \/>\n<meta property=\"og:url\" content=\"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-17T15:02:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-22T16:45:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/meta-m.org\/wp-content\/uploads\/2017\/12\/malta-protest-daphne-caruana-galizia_4135888.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"1 minute\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/meta-m.org\/#website\",\"url\":\"https:\/\/meta-m.org\/\",\"name\":\"\",\"description\":\"&quot;Parce que la v\\u00e9rit\\u00e9 se meurt dans le silence...&quot;\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/meta-m.org\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/meta-m.org\/wp-content\/uploads\/2017\/12\/malta-protest-daphne-caruana-galizia_4135888.jpg\",\"width\":1600,\"height\":900,\"caption\":\"A woman holds up a banner with a quote from murdered Maltese journalist and anti-corruption blogger Daphne Caruana Galizia's blog during a national rally to demand justice for her killing in the island's capital Valletta on October 22, 2017. Galizia, 53, a prominent Maltese journalist and blogger who made repeated and detailed corruption allegations against Prime Minister Joseph Muscat's inner circle, was killed by a car bomb on October 16, 2017. \/ AFP PHOTO \/ Matthew Mirabelli \/ Malta OUT (Photo credit should read MATTHEW MIRABELLI\/AFP\/Getty Images)\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/#webpage\",\"url\":\"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/\",\"name\":\"Malte, une \\u00eele gangr\\u00e9n\\u00e9e par la corruption ? -\",\"isPartOf\":{\"@id\":\"https:\/\/meta-m.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/#primaryimage\"},\"datePublished\":\"2017-12-17T15:02:41+00:00\",\"dateModified\":\"2017-12-22T16:45:53+00:00\",\"author\":{\"@id\":\"https:\/\/meta-m.org\/#\/schema\/person\/0fb32fc8243490c04a83a9c267f71301\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/meta-m.org\/index.php\/2017\/12\/17\/malte-une-ile-gangrenee-par-la-corruption\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/meta-m.org\/#\/schema\/person\/0fb32fc8243490c04a83a9c267f71301\",\"name\":\"Collectif MetaMorphosis\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/meta-m.org\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/77666b7f3b848298ef70b0893925bb93?s=96&d=mm&r=g\",\"caption\":\"Collectif MetaMorphosis\"},\"description\":\"Nous sommes un collectif apolitique de lanceurs d\\u2019alerte qui souhaite partager ses exp\\u00e9riences pour mettre en \\u0153uvre un outil citoyen permettant d\\u2019accompagner les lanceurs et d\\u2019informer le public. Le collectif est \\u00e9paul\\u00e9 par des professionnels, avocats, journalistes d\\u2019investigation, et associations d\\u00e9di\\u00e9es \\u00e0 l\\u2019alerte.\",\"sameAs\":[\"https:\/\/meta-m.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/posts\/1886"}],"collection":[{"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/comments?post=1886"}],"version-history":[{"count":9,"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/posts\/1886\/revisions"}],"predecessor-version":[{"id":1968,"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/posts\/1886\/revisions\/1968"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/media\/1894"}],"wp:attachment":[{"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/media?parent=1886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/categories?post=1886"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/meta-m.org\/index.php\/wp-json\/wp\/v2\/tags?post=1886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}